{"id":8881,"count":0,"description":"","link":"https:\/\/silicon-saxony.de\/en\/zielmaerkte\/sputtertechnologien-en\/","name":"Sputtertechnologien","slug":"sputtertechnologien-en","taxonomy":"zielmaerkte","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sputtertechnologien Archive - Silicon Saxony<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sputtertechnologien Archive - Silicon Saxony\" \/>\n<meta property=\"og:url\" content=\"https:\/\/silicon-saxony.de\/en\/zielmaerkte\/sputtertechnologien-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Silicon Saxony\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/zielmaerkte\/sputtertechnologien-en\/\",\"url\":\"https:\/\/silicon-saxony.de\/en\/zielmaerkte\/sputtertechnologien-en\/\",\"name\":\"Sputtertechnologien Archive - Silicon Saxony\",\"isPartOf\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/zielmaerkte\/sputtertechnologien-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/zielmaerkte\/sputtertechnologien-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/silicon-saxony.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sputtertechnologien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\",\"url\":\"https:\/\/silicon-saxony.de\/en\/\",\"name\":\"Silicon Saxony\",\"description\":\"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sputtertechnologien Archive - Silicon Saxony","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Sputtertechnologien Archive - Silicon Saxony","og_url":"https:\/\/silicon-saxony.de\/en\/zielmaerkte\/sputtertechnologien-en\/","og_site_name":"Silicon Saxony","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/silicon-saxony.de\/en\/zielmaerkte\/sputtertechnologien-en\/","url":"https:\/\/silicon-saxony.de\/en\/zielmaerkte\/sputtertechnologien-en\/","name":"Sputtertechnologien Archive - Silicon Saxony","isPartOf":{"@id":"https:\/\/silicon-saxony.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/silicon-saxony.de\/en\/zielmaerkte\/sputtertechnologien-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/silicon-saxony.de\/en\/zielmaerkte\/sputtertechnologien-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/silicon-saxony.de\/en\/"},{"@type":"ListItem","position":2,"name":"Sputtertechnologien"}]},{"@type":"WebSite","@id":"https:\/\/silicon-saxony.de\/en\/#website","url":"https:\/\/silicon-saxony.de\/en\/","name":"Silicon Saxony","description":"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zielmaerkte\/8881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zielmaerkte"}],"about":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/taxonomies\/zielmaerkte"}],"wp:post_type":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder?zielmaerkte=8881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}