{"id":7437,"date":"2024-09-09T12:35:03","date_gmt":"2024-09-09T10:35:03","guid":{"rendered":"https:\/\/silicon-saxony.de\/mitglieder\/tu-dresden-ihm-2\/"},"modified":"2024-09-09T12:35:04","modified_gmt":"2024-09-09T10:35:04","slug":"tu-dresden-ihm-2","status":"publish","type":"mitglieder","link":"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/","title":{"rendered":"TU Dresden, Institut f\u00fcr Halbleiter- und Mikrosystemtechnik (IHM)"},"content":{"rendered":"","protected":false},"featured_media":277432,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_links_to":"","_links_to_target":""},"categories":[17,1],"tags":[],"initialie":[313],"kompetenzen":[6849,9905,6714,6712,7991],"mitgliedsart":[6681],"portfolio":[10118,10540,7302,6679,6678,6651,6998,10539,6650,10538],"taetigkeitsfelder":[8057,7265,6711],"unternehmensart":[8403],"zertifikate":[],"zielmaerkte":[6851,7339,6670],"class_list":["post-7437","mitglieder","type-mitglieder","status-publish","has-post-thumbnail","hentry","category-uncategorized","category-unkategorisiert","initialie-t","kompetenzen-electronics-en","kompetenzen-ic-design-en","kompetenzen-manufacturing-en","kompetenzen-semiconductor-en","kompetenzen-system-design-en","mitgliedsart-members-en","portfolio-atomic-layer-deposition-ald-en","portfolio-back-end-of-line-procsses-en","portfolio-colleges-universities-en","portfolio-electronic-en","portfolio-equipment-en","portfolio-micro-nanoelektronics-en","portfolio-microsystems-technology-en","portfolio-optoelectronic-devices-and-systems-en","portfolio-semiconductor-industry-en","portfolio-semiconductor-technology-en","taetigkeitsfelder-materials-en","taetigkeitsfelder-research-development-en","taetigkeitsfelder-technology-en","unternehmensart-research-institution-en","zielmaerkte-electronics-en","zielmaerkte-public-sector-en","zielmaerkte-services-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TU Dresden, Institut f\u00fcr Halbleiter- und Mikrosystemtechnik (IHM) - Silicon Saxony<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TU Dresden, Institut f\u00fcr Halbleiter- und Mikrosystemtechnik (IHM) - Silicon Saxony\" \/>\n<meta property=\"og:url\" content=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Silicon Saxony\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-09T10:35:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ihm-logo-weisserkasten_1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/\",\"url\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/\",\"name\":\"TU Dresden, Institut f\u00fcr Halbleiter- und Mikrosystemtechnik (IHM) - Silicon Saxony\",\"isPartOf\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ihm-logo-weisserkasten_1-1.png\",\"datePublished\":\"2024-09-09T10:35:03+00:00\",\"dateModified\":\"2024-09-09T10:35:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/#primaryimage\",\"url\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ihm-logo-weisserkasten_1-1.png\",\"contentUrl\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ihm-logo-weisserkasten_1-1.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/silicon-saxony.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mitglieder\",\"item\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TU Dresden, Institut f\u00fcr Halbleiter- und Mikrosystemtechnik (IHM)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\",\"url\":\"https:\/\/silicon-saxony.de\/en\/\",\"name\":\"Silicon Saxony\",\"description\":\"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TU Dresden, Institut f\u00fcr Halbleiter- und Mikrosystemtechnik (IHM) - Silicon Saxony","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/","og_locale":"en_US","og_type":"article","og_title":"TU Dresden, Institut f\u00fcr Halbleiter- und Mikrosystemtechnik (IHM) - Silicon Saxony","og_url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/","og_site_name":"Silicon Saxony","article_modified_time":"2024-09-09T10:35:04+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ihm-logo-weisserkasten_1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/","url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/","name":"TU Dresden, Institut f\u00fcr Halbleiter- und Mikrosystemtechnik (IHM) - Silicon Saxony","isPartOf":{"@id":"https:\/\/silicon-saxony.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/#primaryimage"},"image":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/#primaryimage"},"thumbnailUrl":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ihm-logo-weisserkasten_1-1.png","datePublished":"2024-09-09T10:35:03+00:00","dateModified":"2024-09-09T10:35:04+00:00","breadcrumb":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/#primaryimage","url":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ihm-logo-weisserkasten_1-1.png","contentUrl":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ihm-logo-weisserkasten_1-1.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/tu-dresden-ihm-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/silicon-saxony.de\/en\/"},{"@type":"ListItem","position":2,"name":"Mitglieder","item":"https:\/\/silicon-saxony.de\/en\/mitglieder\/"},{"@type":"ListItem","position":3,"name":"TU Dresden, Institut f\u00fcr Halbleiter- und Mikrosystemtechnik (IHM)"}]},{"@type":"WebSite","@id":"https:\/\/silicon-saxony.de\/en\/#website","url":"https:\/\/silicon-saxony.de\/en\/","name":"Silicon Saxony","description":"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder\/7437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder"}],"about":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/types\/mitglieder"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/media\/277432"}],"wp:attachment":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/media?parent=7437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/categories?post=7437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/tags?post=7437"},{"taxonomy":"initialie","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/initialie?post=7437"},{"taxonomy":"kompetenzen","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/kompetenzen?post=7437"},{"taxonomy":"mitgliedsart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitgliedsart?post=7437"},{"taxonomy":"portfolio","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/portfolio?post=7437"},{"taxonomy":"taetigkeitsfelder","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/taetigkeitsfelder?post=7437"},{"taxonomy":"unternehmensart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/unternehmensart?post=7437"},{"taxonomy":"zertifikate","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zertifikate?post=7437"},{"taxonomy":"zielmaerkte","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zielmaerkte?post=7437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}