{"id":6759,"date":"2024-07-30T11:15:31","date_gmt":"2024-07-30T09:15:31","guid":{"rendered":"https:\/\/silicon-saxony.de\/mitglieder\/kuka-deutschland-gmbh-2\/"},"modified":"2024-07-30T11:15:32","modified_gmt":"2024-07-30T09:15:32","slug":"kuka-deutschland-gmbh-2","status":"publish","type":"mitglieder","link":"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/","title":{"rendered":"KUKA Deutschland GmbH"},"content":{"rendered":"","protected":false},"featured_media":244392,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_links_to":"","_links_to_target":""},"categories":[17,1],"tags":[],"initialie":[306],"kompetenzen":[8621,6849,6850,8620,6712],"mitgliedsart":[6681],"portfolio":[6719,6677,6679,6678,6827,6650,6675],"taetigkeitsfelder":[6710],"unternehmensart":[6829],"zertifikate":[],"zielmaerkte":[6851,6715,7306],"class_list":["post-6759","mitglieder","type-mitglieder","status-publish","has-post-thumbnail","hentry","category-uncategorized","category-unkategorisiert","initialie-k","kompetenzen-automation-en","kompetenzen-electronics-en","kompetenzen-machinery-plant-engineering-en","kompetenzen-robotics-en","kompetenzen-semiconductor-en","mitgliedsart-members-en","portfolio-applications-en","portfolio-computers-en","portfolio-electronic-en","portfolio-equipment-en","portfolio-rail-automotive-en","portfolio-semiconductor-industry-en","portfolio-software-en","taetigkeitsfelder-machinery-equipment-en","unternehmensart-large-companies-250-employees-or-50-million-annual-sales-en","zielmaerkte-electronics-en","zielmaerkte-machinery-and-equipment-en","zielmaerkte-mobility-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KUKA Deutschland GmbH - Silicon Saxony<\/title>\n<meta name=\"description\" content=\"KUKA stands for ideas and innovations made in Germany. Today, KUKA is one of the world&#039;s leading suppliers of intelligent automation solutions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KUKA Deutschland GmbH - Silicon Saxony\" \/>\n<meta property=\"og:description\" content=\"KUKA stands for ideas and innovations made in Germany. Today, KUKA is one of the world&#039;s leading suppliers of intelligent automation solutions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Silicon Saxony\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T09:15:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/kuka-logo-300x300-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/\",\"url\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/\",\"name\":\"KUKA Deutschland GmbH - Silicon Saxony\",\"isPartOf\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/kuka-logo-300x300-2.jpg\",\"datePublished\":\"2024-07-30T09:15:31+00:00\",\"dateModified\":\"2024-07-30T09:15:32+00:00\",\"description\":\"KUKA stands for ideas and innovations made in Germany. Today, KUKA is one of the world's leading suppliers of intelligent automation solutions.\",\"breadcrumb\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/#primaryimage\",\"url\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/kuka-logo-300x300-2.jpg\",\"contentUrl\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/kuka-logo-300x300-2.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/silicon-saxony.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mitglieder\",\"item\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KUKA Deutschland GmbH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\",\"url\":\"https:\/\/silicon-saxony.de\/en\/\",\"name\":\"Silicon Saxony\",\"description\":\"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KUKA Deutschland GmbH - Silicon Saxony","description":"KUKA stands for ideas and innovations made in Germany. Today, KUKA is one of the world's leading suppliers of intelligent automation solutions.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/","og_locale":"en_US","og_type":"article","og_title":"KUKA Deutschland GmbH - Silicon Saxony","og_description":"KUKA stands for ideas and innovations made in Germany. Today, KUKA is one of the world's leading suppliers of intelligent automation solutions.","og_url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/","og_site_name":"Silicon Saxony","article_modified_time":"2024-07-30T09:15:32+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/kuka-logo-300x300-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/","url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/","name":"KUKA Deutschland GmbH - Silicon Saxony","isPartOf":{"@id":"https:\/\/silicon-saxony.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/#primaryimage"},"image":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/#primaryimage"},"thumbnailUrl":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/kuka-logo-300x300-2.jpg","datePublished":"2024-07-30T09:15:31+00:00","dateModified":"2024-07-30T09:15:32+00:00","description":"KUKA stands for ideas and innovations made in Germany. Today, KUKA is one of the world's leading suppliers of intelligent automation solutions.","breadcrumb":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/#primaryimage","url":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/kuka-logo-300x300-2.jpg","contentUrl":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/kuka-logo-300x300-2.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/kuka-deutschland-gmbh-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/silicon-saxony.de\/en\/"},{"@type":"ListItem","position":2,"name":"Mitglieder","item":"https:\/\/silicon-saxony.de\/en\/mitglieder\/"},{"@type":"ListItem","position":3,"name":"KUKA Deutschland GmbH"}]},{"@type":"WebSite","@id":"https:\/\/silicon-saxony.de\/en\/#website","url":"https:\/\/silicon-saxony.de\/en\/","name":"Silicon Saxony","description":"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder\/6759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder"}],"about":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/types\/mitglieder"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/media\/244392"}],"wp:attachment":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/media?parent=6759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/categories?post=6759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/tags?post=6759"},{"taxonomy":"initialie","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/initialie?post=6759"},{"taxonomy":"kompetenzen","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/kompetenzen?post=6759"},{"taxonomy":"mitgliedsart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitgliedsart?post=6759"},{"taxonomy":"portfolio","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/portfolio?post=6759"},{"taxonomy":"taetigkeitsfelder","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/taetigkeitsfelder?post=6759"},{"taxonomy":"unternehmensart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/unternehmensart?post=6759"},{"taxonomy":"zertifikate","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zertifikate?post=6759"},{"taxonomy":"zielmaerkte","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zielmaerkte?post=6759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}