{"id":6359,"date":"2026-03-02T13:42:46","date_gmt":"2026-03-02T12:42:46","guid":{"rendered":"https:\/\/silicon-saxony.de\/mitglieder\/edacentrum-e-v-2\/"},"modified":"2026-03-02T13:42:47","modified_gmt":"2026-03-02T12:42:47","slug":"edacentrum-e-v-2","status":"publish","type":"mitglieder","link":"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/","title":{"rendered":"edacentrum e.V."},"content":{"rendered":"","protected":false},"featured_media":227282,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_links_to":"","_links_to_target":""},"categories":[17,1],"tags":[],"initialie":[303],"kompetenzen":[6849,8981,6712],"mitgliedsart":[6681],"portfolio":[6885,8360,7885,6651,6976,8052,6650],"taetigkeitsfelder":[7265],"unternehmensart":[6837],"zertifikate":[],"zielmaerkte":[6670],"class_list":["post-6359","mitglieder","type-mitglieder","status-publish","has-post-thumbnail","hentry","category-uncategorized","category-unkategorisiert","initialie-e","kompetenzen-electronics-en","kompetenzen-nanoelectronics-en","kompetenzen-semiconductor-en","mitgliedsart-members-en","portfolio-consulting-en","portfolio-eda-clusterforschung-en-en","portfolio-electronic-design-automation-eda-en-en","portfolio-micro-nanoelektronics-en","portfolio-networks-en","portfolio-project-management-en","portfolio-semiconductor-industry-en","taetigkeitsfelder-research-development-en","unternehmensart-small-companies","zielmaerkte-services-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>edacentrum e.V. - Silicon Saxony<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"edacentrum e.V. - Silicon Saxony\" \/>\n<meta property=\"og:url\" content=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Silicon Saxony\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T12:42:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/edacentrum-logo-300x300-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/\",\"url\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/\",\"name\":\"edacentrum e.V. - Silicon Saxony\",\"isPartOf\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/edacentrum-logo-300x300-2.jpg\",\"datePublished\":\"2026-03-02T12:42:46+00:00\",\"dateModified\":\"2026-03-02T12:42:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/#primaryimage\",\"url\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/edacentrum-logo-300x300-2.jpg\",\"contentUrl\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/edacentrum-logo-300x300-2.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/silicon-saxony.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mitglieder\",\"item\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"edacentrum e.V.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\",\"url\":\"https:\/\/silicon-saxony.de\/en\/\",\"name\":\"Silicon Saxony\",\"description\":\"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"edacentrum e.V. - Silicon Saxony","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/","og_locale":"en_US","og_type":"article","og_title":"edacentrum e.V. - Silicon Saxony","og_url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/","og_site_name":"Silicon Saxony","article_modified_time":"2026-03-02T12:42:47+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/edacentrum-logo-300x300-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/","url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/","name":"edacentrum e.V. - Silicon Saxony","isPartOf":{"@id":"https:\/\/silicon-saxony.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/#primaryimage"},"image":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/#primaryimage"},"thumbnailUrl":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/edacentrum-logo-300x300-2.jpg","datePublished":"2026-03-02T12:42:46+00:00","dateModified":"2026-03-02T12:42:47+00:00","breadcrumb":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/#primaryimage","url":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/edacentrum-logo-300x300-2.jpg","contentUrl":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/edacentrum-logo-300x300-2.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/edacentrum-e-v-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/silicon-saxony.de\/en\/"},{"@type":"ListItem","position":2,"name":"Mitglieder","item":"https:\/\/silicon-saxony.de\/en\/mitglieder\/"},{"@type":"ListItem","position":3,"name":"edacentrum e.V."}]},{"@type":"WebSite","@id":"https:\/\/silicon-saxony.de\/en\/#website","url":"https:\/\/silicon-saxony.de\/en\/","name":"Silicon Saxony","description":"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder\/6359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder"}],"about":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/types\/mitglieder"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/media\/227282"}],"wp:attachment":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/media?parent=6359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/categories?post=6359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/tags?post=6359"},{"taxonomy":"initialie","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/initialie?post=6359"},{"taxonomy":"kompetenzen","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/kompetenzen?post=6359"},{"taxonomy":"mitgliedsart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitgliedsart?post=6359"},{"taxonomy":"portfolio","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/portfolio?post=6359"},{"taxonomy":"taetigkeitsfelder","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/taetigkeitsfelder?post=6359"},{"taxonomy":"unternehmensart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/unternehmensart?post=6359"},{"taxonomy":"zertifikate","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zertifikate?post=6359"},{"taxonomy":"zielmaerkte","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zielmaerkte?post=6359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}