{"id":5951,"date":"2024-07-02T14:56:40","date_gmt":"2024-07-02T12:56:40","guid":{"rendered":"https:\/\/silicon-saxony.de\/mitglieder\/applied-materials-gmbh-2\/"},"modified":"2024-07-02T14:56:41","modified_gmt":"2024-07-02T12:56:41","slug":"applied-materials-gmbh-2","status":"publish","type":"mitglieder","link":"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/","title":{"rendered":"Applied Materials GmbH"},"content":{"rendered":"","protected":false},"featured_media":214781,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_links_to":"","_links_to_target":""},"categories":[17,1],"tags":[],"initialie":[188],"kompetenzen":[6712],"mitgliedsart":[6681],"portfolio":[7084,6679,7081,6826,6678,7082,6651,6718,7083,6650],"taetigkeitsfelder":[7902],"unternehmensart":[6829],"zertifikate":[],"zielmaerkte":[6851],"class_list":["post-5951","mitglieder","type-mitglieder","status-publish","has-post-thumbnail","hentry","category-uncategorized","category-unkategorisiert","initialie-a","kompetenzen-semiconductor-en","mitgliedsart-members-en","portfolio-displays-en","portfolio-electronic-en","portfolio-energy-environment-en","portfolio-environmental-technoloy-en","portfolio-equipment-en","portfolio-fab-solutions-en","portfolio-micro-nanoelektronics-en","portfolio-photovoltaics-en","portfolio-semiconductor-en","portfolio-semiconductor-industry-en","taetigkeitsfelder-production-en","unternehmensart-large-companies-250-employees-or-50-million-annual-sales-en","zielmaerkte-electronics-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Applied Materials GmbH - Silicon Saxony<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Applied Materials GmbH - Silicon Saxony\" \/>\n<meta property=\"og:url\" content=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Silicon Saxony\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T12:56:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/appliedmaterials-logo-300x300-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/\",\"url\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/\",\"name\":\"Applied Materials GmbH - Silicon Saxony\",\"isPartOf\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/appliedmaterials-logo-300x300-3.jpg\",\"datePublished\":\"2024-07-02T12:56:40+00:00\",\"dateModified\":\"2024-07-02T12:56:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/#primaryimage\",\"url\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/appliedmaterials-logo-300x300-3.jpg\",\"contentUrl\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/appliedmaterials-logo-300x300-3.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/silicon-saxony.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mitglieder\",\"item\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Applied Materials GmbH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\",\"url\":\"https:\/\/silicon-saxony.de\/en\/\",\"name\":\"Silicon Saxony\",\"description\":\"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Applied Materials GmbH - Silicon Saxony","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/","og_locale":"en_US","og_type":"article","og_title":"Applied Materials GmbH - Silicon Saxony","og_url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/","og_site_name":"Silicon Saxony","article_modified_time":"2024-07-02T12:56:41+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/appliedmaterials-logo-300x300-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/","url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/","name":"Applied Materials GmbH - Silicon Saxony","isPartOf":{"@id":"https:\/\/silicon-saxony.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/#primaryimage"},"image":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/#primaryimage"},"thumbnailUrl":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/appliedmaterials-logo-300x300-3.jpg","datePublished":"2024-07-02T12:56:40+00:00","dateModified":"2024-07-02T12:56:41+00:00","breadcrumb":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/#primaryimage","url":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/appliedmaterials-logo-300x300-3.jpg","contentUrl":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/07\/appliedmaterials-logo-300x300-3.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/applied-materials-gmbh-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/silicon-saxony.de\/en\/"},{"@type":"ListItem","position":2,"name":"Mitglieder","item":"https:\/\/silicon-saxony.de\/en\/mitglieder\/"},{"@type":"ListItem","position":3,"name":"Applied Materials GmbH"}]},{"@type":"WebSite","@id":"https:\/\/silicon-saxony.de\/en\/#website","url":"https:\/\/silicon-saxony.de\/en\/","name":"Silicon Saxony","description":"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder\/5951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder"}],"about":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/types\/mitglieder"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/media\/214781"}],"wp:attachment":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/media?parent=5951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/categories?post=5951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/tags?post=5951"},{"taxonomy":"initialie","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/initialie?post=5951"},{"taxonomy":"kompetenzen","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/kompetenzen?post=5951"},{"taxonomy":"mitgliedsart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitgliedsart?post=5951"},{"taxonomy":"portfolio","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/portfolio?post=5951"},{"taxonomy":"taetigkeitsfelder","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/taetigkeitsfelder?post=5951"},{"taxonomy":"unternehmensart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/unternehmensart?post=5951"},{"taxonomy":"zertifikate","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zertifikate?post=5951"},{"taxonomy":"zielmaerkte","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zielmaerkte?post=5951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}