{"id":532103,"date":"2025-12-08T16:49:19","date_gmt":"2025-12-08T15:49:19","guid":{"rendered":"https:\/\/silicon-saxony.de\/mitglieder\/s-a-t-srl-2\/"},"modified":"2025-12-08T16:49:19","modified_gmt":"2025-12-08T15:49:19","slug":"s-a-t-srl-2","status":"publish","type":"mitglieder","link":"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/","title":{"rendered":"S.A.T. srl"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_links_to":"","_links_to_target":""},"categories":[],"tags":[],"initialie":[],"kompetenzen":[6849,6713,6712],"mitgliedsart":[6681],"portfolio":[11549,7083,9376],"taetigkeitsfelder":[8057,7902,6711],"unternehmensart":[6837],"zertifikate":[],"zielmaerkte":[6851],"class_list":["post-532103","mitglieder","type-mitglieder","status-publish","hentry","kompetenzen-electronics-en","kompetenzen-process-technologies-en","kompetenzen-semiconductor-en","mitgliedsart-members-en","portfolio-photovoltaic-en","portfolio-semiconductor-en","portfolio-solar-en","taetigkeitsfelder-materials-en","taetigkeitsfelder-production-en","taetigkeitsfelder-technology-en","unternehmensart-small-companies","zielmaerkte-electronics-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S.A.T. srl - Silicon Saxony<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S.A.T. srl - Silicon Saxony\" \/>\n<meta property=\"og:url\" content=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Silicon Saxony\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/\",\"url\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/\",\"name\":\"S.A.T. srl - Silicon Saxony\",\"isPartOf\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\"},\"datePublished\":\"2025-12-08T15:49:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/silicon-saxony.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mitglieder\",\"item\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S.A.T. srl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\",\"url\":\"https:\/\/silicon-saxony.de\/en\/\",\"name\":\"Silicon Saxony\",\"description\":\"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S.A.T. srl - Silicon Saxony","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/","og_locale":"en_US","og_type":"article","og_title":"S.A.T. srl - Silicon Saxony","og_url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/","og_site_name":"Silicon Saxony","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/","url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/","name":"S.A.T. srl - Silicon Saxony","isPartOf":{"@id":"https:\/\/silicon-saxony.de\/en\/#website"},"datePublished":"2025-12-08T15:49:19+00:00","breadcrumb":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/s-a-t-srl-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/silicon-saxony.de\/en\/"},{"@type":"ListItem","position":2,"name":"Mitglieder","item":"https:\/\/silicon-saxony.de\/en\/mitglieder\/"},{"@type":"ListItem","position":3,"name":"S.A.T. srl"}]},{"@type":"WebSite","@id":"https:\/\/silicon-saxony.de\/en\/#website","url":"https:\/\/silicon-saxony.de\/en\/","name":"Silicon Saxony","description":"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder\/532103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder"}],"about":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/types\/mitglieder"}],"wp:attachment":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/media?parent=532103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/categories?post=532103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/tags?post=532103"},{"taxonomy":"initialie","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/initialie?post=532103"},{"taxonomy":"kompetenzen","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/kompetenzen?post=532103"},{"taxonomy":"mitgliedsart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitgliedsart?post=532103"},{"taxonomy":"portfolio","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/portfolio?post=532103"},{"taxonomy":"taetigkeitsfelder","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/taetigkeitsfelder?post=532103"},{"taxonomy":"unternehmensart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/unternehmensart?post=532103"},{"taxonomy":"zertifikate","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zertifikate?post=532103"},{"taxonomy":"zielmaerkte","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zielmaerkte?post=532103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}