{"id":227765,"date":"2025-10-13T18:01:08","date_gmt":"2025-10-13T16:01:08","guid":{"rendered":"https:\/\/silicon-saxony.de\/mitglieder\/ferrotec-europe-gmbh-2\/"},"modified":"2025-10-13T18:01:08","modified_gmt":"2025-10-13T16:01:08","slug":"ferrotec-europe-gmbh-2","status":"publish","type":"mitglieder","link":"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/","title":{"rendered":"Ferrotec Europe GmbH"},"content":{"rendered":"","protected":false},"featured_media":273333,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_links_to":"","_links_to_target":""},"categories":[17],"tags":[],"initialie":[],"kompetenzen":[6849,6850],"mitgliedsart":[6681],"portfolio":[10882,7083],"taetigkeitsfelder":[8057,6711,8232],"unternehmensart":[6731],"zertifikate":[],"zielmaerkte":[6851,6715],"class_list":["post-227765","mitglieder","type-mitglieder","status-publish","has-post-thumbnail","hentry","category-uncategorized","kompetenzen-electronics-en","kompetenzen-machinery-plant-engineering-en","mitgliedsart-members-en","portfolio-electronics-en","portfolio-semiconductor-en","taetigkeitsfelder-materials-en","taetigkeitsfelder-technology-en","taetigkeitsfelder-upstream-industry-en","unternehmensart-medium-sized-companies","zielmaerkte-electronics-en","zielmaerkte-machinery-and-equipment-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ferrotec Europe GmbH - Silicon Saxony<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferrotec Europe GmbH - Silicon Saxony\" \/>\n<meta property=\"og:url\" content=\"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Silicon Saxony\" \/>\n<meta property=\"og:image\" content=\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ferrotec-logo-300x300-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/\",\"url\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/\",\"name\":\"Ferrotec Europe GmbH - Silicon Saxony\",\"isPartOf\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ferrotec-logo-300x300-1.jpg\",\"datePublished\":\"2025-10-13T16:01:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/#primaryimage\",\"url\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ferrotec-logo-300x300-1.jpg\",\"contentUrl\":\"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ferrotec-logo-300x300-1.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/silicon-saxony.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mitglieder\",\"item\":\"https:\/\/silicon-saxony.de\/en\/mitglieder\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferrotec Europe GmbH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/silicon-saxony.de\/en\/#website\",\"url\":\"https:\/\/silicon-saxony.de\/en\/\",\"name\":\"Silicon Saxony\",\"description\":\"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferrotec Europe GmbH - Silicon Saxony","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/","og_locale":"en_US","og_type":"article","og_title":"Ferrotec Europe GmbH - Silicon Saxony","og_url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/","og_site_name":"Silicon Saxony","og_image":[{"width":300,"height":300,"url":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ferrotec-logo-300x300-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/","url":"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/","name":"Ferrotec Europe GmbH - Silicon Saxony","isPartOf":{"@id":"https:\/\/silicon-saxony.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/#primaryimage"},"image":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/#primaryimage"},"thumbnailUrl":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ferrotec-logo-300x300-1.jpg","datePublished":"2025-10-13T16:01:08+00:00","breadcrumb":{"@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/#primaryimage","url":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ferrotec-logo-300x300-1.jpg","contentUrl":"https:\/\/silicon-saxony.de\/wp-content\/uploads\/2024\/09\/ferrotec-logo-300x300-1.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/silicon-saxony.de\/en\/mitglieder\/ferrotec-europe-gmbh-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/silicon-saxony.de\/en\/"},{"@type":"ListItem","position":2,"name":"Mitglieder","item":"https:\/\/silicon-saxony.de\/en\/mitglieder\/"},{"@type":"ListItem","position":3,"name":"Ferrotec Europe GmbH"}]},{"@type":"WebSite","@id":"https:\/\/silicon-saxony.de\/en\/#website","url":"https:\/\/silicon-saxony.de\/en\/","name":"Silicon Saxony","description":"Germany&#039;s Hightech Network - Semiconductors, Software, Robotics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/silicon-saxony.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder\/227765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitglieder"}],"about":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/types\/mitglieder"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/media\/273333"}],"wp:attachment":[{"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/media?parent=227765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/categories?post=227765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/tags?post=227765"},{"taxonomy":"initialie","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/initialie?post=227765"},{"taxonomy":"kompetenzen","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/kompetenzen?post=227765"},{"taxonomy":"mitgliedsart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/mitgliedsart?post=227765"},{"taxonomy":"portfolio","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/portfolio?post=227765"},{"taxonomy":"taetigkeitsfelder","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/taetigkeitsfelder?post=227765"},{"taxonomy":"unternehmensart","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/unternehmensart?post=227765"},{"taxonomy":"zertifikate","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zertifikate?post=227765"},{"taxonomy":"zielmaerkte","embeddable":true,"href":"https:\/\/silicon-saxony.de\/en\/wp-json\/wp\/v2\/zielmaerkte?post=227765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}